{"id":5474,"date":"2020-11-04T12:00:56","date_gmt":"2020-11-04T11:00:56","guid":{"rendered":"https:\/\/www.ruedustore.fr\/blog\/?p=5474"},"modified":"2023-07-20T15:04:31","modified_gmt":"2023-07-20T13:04:31","slug":"couleur-oh-couleur-dis-moi-qui-est-la-plus-tendance-cet-hiver","status":"publish","type":"post","link":"https:\/\/www.ruedustore.fr\/blog\/couleur-oh-couleur-dis-moi-qui-est-la-plus-tendance-cet-hiver\/","title":{"rendered":"Couleur, oh couleur, dis-moi qui est la plus tendance cet hiver ?"},"content":{"rendered":"<p>L&rsquo;int\u00e9rieur des Fran\u00e7ais est de plus en plus blanc. Ce n&rsquo;est pas \u00e9tonnant, le blanc est ind\u00e9modable et si efficace. Consid\u00e9r\u00e9 comme une couleur froide, en hiver, il peut vite mettre notre moral en berne.\u00a0Alors que diriez-vous de quitter votre zone de confort et de d\u00e9couvrir avec nous les tendances couleurs 2020\/2021 ?<\/p>\n<p><a href=\"https:\/\/www.ruedustore.fr\/\">Rue du Store<\/a> vous accompagne tout en douceur pour cette transition color\u00e9e.<\/p>\n<h2>La chaleur de la Terracotta<\/h2>\n<p>Elle est enfin de retour ! Cette nuance \u00e0 mi-chemin entre le rouge et le orange nous avait manqu\u00e9. Comme un petit go\u00fbt de vacances en Italie au mois d&rsquo;ao\u00fbt, gorg\u00e9e de soleil et de douceur . La terracotta se mariera parfaitement avec votre <a href=\"https:\/\/www.ruedustore.fr\/store-interieur.html\">int\u00e9rieur<\/a>. Elle trouvera tout son charme en petites touches, sur un coussin, un vase, un tableau g\u00e9om\u00e9trique ou un tapis en fibre naturelle. Dans le salon comme dans la chambre, son ton apportera chaleur dans votre foyer.\u00a0 Petite astuce : La marier avec un rose poudr\u00e9 sur des doubles panneaux japonais devant une biblioth\u00e8que peut faire des miracles.<\/p>\n<div id=\"attachment_4576\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4576\" class=\"wp-image-4576 size-medium\" src=\"https:\/\/www.ruedustore.fr\/blog\/wp-content\/uploads\/2020\/01\/TOMO_3-50-300x228.jpg\" alt=\"store-bateau-terracotta\" width=\"300\" height=\"228\" \/><p id=\"caption-attachment-4576\" class=\"wp-caption-text\">Store bateau terracotta 2020<\/p><\/div>\n<p>&nbsp;<\/p>\n<h2>La douceur du Vieux Rose<\/h2>\n<p>Non ce n&rsquo;est pas nouveau, le rose \u00e9tait d\u00e9j\u00e0 pr\u00e9sent la saison derni\u00e8re par petite touche. Mais pour cette saison on en abuse.\u00a0 Fini les petites touches discr\u00e8tes, dites oui au rose fr\u00e9n\u00e9tiquement. On peut aussi le marier \u00e0 la terracotta sans h\u00e9siter, pour un c\u00f4t\u00e9 plus chaleureux. Attention cependant \u00e0 ne pas tomber \u00e0 c\u00f4t\u00e9, le rose est poudr\u00e9, maronn\u00e9, pastel, mais au grand jamais fuchsia ou bonbon. Il se d\u00e9clinera dans toutes les pi\u00e8ces, avec une pr\u00e9f\u00e9rence pour le velours et les mati\u00e8res nobles ou naturelles. Petite astuce : le rose \u00e9tant une couleur chaude, l&rsquo;apposer sur un <a href=\"https:\/\/www.ruedustore.fr\/store-enrouleur.html\">store enrouleur<\/a> ou un panneau japonais fera \u00e0 coup sur une ambiance chaleureuse dans votre pi\u00e8ce \u00e0 vivre.<\/p>\n<div id=\"attachment_5480\" style=\"width: 235px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5480\" class=\"wp-image-5480 size-medium\" src=\"https:\/\/www.ruedustore.fr\/blog\/wp-content\/uploads\/2020\/09\/IMG_1319-225x300.jpg\" alt=\"nuances-de-roses\" width=\"225\" height=\"300\" \/><p id=\"caption-attachment-5480\" class=\"wp-caption-text\">Nuancier de roses, Rue Du Store 2020\/2021<\/p><\/div>\n<h2>Le naturel du Vert<\/h2>\n<p>Il n&rsquo;avait jamais vraiment quitt\u00e9 notre int\u00e9rieur, toujours plus ou moins l\u00e0. Mais cette ann\u00e9e, il reprend (enfin) le devant de la sc\u00e8ne : Le Vert !\u00a0 Le vert est fonc\u00e9, il est kaki, il est naturel, il tire vers le gris ou le bleu, mais en tout cas il est l\u00e0. Par touches de peinture, par pan de mur, ou pour les plus timides sur vos accessoires. Du salon \u00e0 la cuisine, le vert apportera une touche design \u00e0 votre int\u00e9rieur. Petite astuce : le store v\u00e9nitien vert gris dans une cuisine blanche avec quelques cache-pots de nuances de vert-gris au vert-bleu transformera votre pi\u00e8ce.<\/p>\n<div id=\"attachment_5479\" style=\"width: 235px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5479\" class=\"wp-image-5479 size-medium\" src=\"https:\/\/www.ruedustore.fr\/blog\/wp-content\/uploads\/2020\/09\/IMG_1321-225x300.jpg\" alt=\"nuances-de-verts\" width=\"225\" height=\"300\" \/><p id=\"caption-attachment-5479\" class=\"wp-caption-text\">Nuancier de verts, Rue Du Store 2020\/2021<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2>La profondeur du Bleu<\/h2>\n<p>Un oubli\u00e9 de nos int\u00e9rieurs depuis plusieurs ann\u00e9es refait surface :\u00a0 le bleu. Il est fonc\u00e9, \u00e9lectrique ou bien tirant vers le vert. Par petites touches discr\u00e8tes ou \u00e0 grands coups de papier peint. Il apportera \u00e0 votre pi\u00e8ce une profondeur et une r\u00e9elle diff\u00e9rence d&rsquo;ambiance selon les teintes choisies. Petite astuce : \u00e0\u00a0marier avec un vieux rose poudr\u00e9 (pour un bleu turquoise pastel) ou un jaune fonc\u00e9 (pour un bleu \u00e9lectrique) , il fera des miracles. Si les sceptiques seront nombreux \u00e0 s&rsquo;interroger sur ma derni\u00e8re proposition, je n&rsquo;ai qu&rsquo;un conseil \u00e0 leur apporter : essayer !<\/p>\n<div id=\"attachment_5058\" style=\"width: 238px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5058\" class=\"size-medium wp-image-5058\" src=\"https:\/\/www.ruedustore.fr\/blog\/wp-content\/uploads\/2020\/06\/Store-venitienv-alu-Select-25mm-salle-a-manger-228x300.jpg\" alt=\"store_venitien-bleu\" width=\"228\" height=\"300\" \/><p id=\"caption-attachment-5058\" class=\"wp-caption-text\">Store v\u00e9nitien bleu 2020<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;int\u00e9rieur des Fran\u00e7ais est de plus en plus blanc. Ce n&rsquo;est pas \u00e9tonnant, le blanc est ind\u00e9modable et si efficace. Consid\u00e9r\u00e9 comme une couleur froide, en hiver, il peut vite mettre notre moral en berne.\u00a0Alors que diriez-vous de quitter votre zone de confort et de d\u00e9couvrir avec nous les tendances couleurs 2020\/2021 ? Rue du&#8230;<a class=\"btnReadMore blake-von-hauer-font-3\" href=\"https:\/\/www.ruedustore.fr\/blog\/couleur-oh-couleur-dis-moi-qui-est-la-plus-tendance-cet-hiver\/\"> Lire la suite<\/a><\/p>\n","protected":false},"author":2,"featured_media":5055,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[89,87],"tags":[],"_links":{"self":[{"href":"https:\/\/www.ruedustore.fr\/blog\/wp-json\/wp\/v2\/posts\/5474"}],"collection":[{"href":"https:\/\/www.ruedustore.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ruedustore.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ruedustore.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ruedustore.fr\/blog\/wp-json\/wp\/v2\/comments?post=5474"}],"version-history":[{"count":14,"href":"https:\/\/www.ruedustore.fr\/blog\/wp-json\/wp\/v2\/posts\/5474\/revisions"}],"predecessor-version":[{"id":7536,"href":"https:\/\/www.ruedustore.fr\/blog\/wp-json\/wp\/v2\/posts\/5474\/revisions\/7536"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ruedustore.fr\/blog\/wp-json\/wp\/v2\/media\/5055"}],"wp:attachment":[{"href":"https:\/\/www.ruedustore.fr\/blog\/wp-json\/wp\/v2\/media?parent=5474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ruedustore.fr\/blog\/wp-json\/wp\/v2\/categories?post=5474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ruedustore.fr\/blog\/wp-json\/wp\/v2\/tags?post=5474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}